{"id":17565,"date":"2019-03-19T18:21:23","date_gmt":"2019-03-20T01:21:23","guid":{"rendered":"https:\/\/live-canadian-association-of-snowboard-instructors.pantheonsite.io\/casi-blog\/la-suisse\/"},"modified":"2023-12-13T15:37:01","modified_gmt":"2023-12-13T23:37:01","slug":"la-suisse","status":"publish","type":"post","link":"https:\/\/casi-acms.com\/fr\/casi-interski\/la-suisse\/","title":{"rendered":"La Suisse!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" class=\"lede\">Journ\u00e9e 3 du congr\u00e8s Interski et aujourd&#8217;hui j&#8217;ai eu le plaisir d&#8217;assister \u00e0 la session sur neige de l&#8217;\u00e9quipe Suisse, un pays qui est toujours tr\u00e8s branch\u00e9 et toujours en recherche d&#8217;innovation pour am\u00e9liorer l&#8217;experience des \u00e9tudiants des \u00e9coles de glisse de la Suisse, c&#8217;est bien aussi de jaser en Fran\u00e7ais avec eux, un de leurs languages officiel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le but de leur session \u00e9tais de partager leur fa\u00e7on d&#8217;enseigner un mouvement ou une manoeuvre de fa\u00e7on simple et efficace; la manoeuvre du jour&#8230; Le Harry. Le Harry est facilement d\u00e9crit come un nose press avec un backside shifty. Le but \u00e9tait de cr\u00e9er une position stable en nose press et en m\u00eame temps envoyer le tail en contre rotation avec le haut du corps et une extension de la jambe avant pour produire un effet dramatique et un style sans \u00e9gal! Assez difficile pour nous garder engag\u00e9!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La m\u00e9thode d&#8217;enseignement fut simple&#8230; 1: On essais la manoeuvre apr\u00e8s avoir vu une d\u00e9mo. Sur une piste verte dam\u00e9e, cons\u00e9quences potentielle minimale. On en discute, on \u00e9change des impressions et on pose des questions&#8230;Similaire \u00e0 la d\u00e9couverte guid\u00e9e. 2: <em><strong>Quelle sorte de m\u00e9thodes d&#8217;apprentissage sont les plus efficaces et quand les mettre en pratique? <\/strong><\/em>On d\u00e9construit la manoeuvre en \u00e9tape. Sur une surface plate on commence avec un nose press, on explore l&#8217;amplitude des movements avant, la position des hanches et les sensations recherch\u00e9es. On se met par deux et on va encore plus loin dans notre amplitude et on ajoute le shifty, mon partenaire me tenant les deux mains pour stabilit\u00e9 lorsque nous somme statique; pas facile! Nous sommes en <strong>Acquisition<\/strong> des mouvements. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3: On glisse! Maintenant c&#8217;est le temps de mettre les mouvements acquis en pratique, toujours sur du terrain vert ou les cons\u00e9quences sont basse pour assurer une performance optimale. On nous donne beaucoup de temps pour la <strong>Consolidation<\/strong> des mouvements de la manoeuvre. 4: <strong>Application et Variation<\/strong> des mouvements (manoeuvre): <em><strong>Comment individualiser l&#8217;enseignement pour pouvoir adresser tout les types d&#8217;apprentissage?<\/strong> <\/em>On trouve des analogies pour contribuer davantage \u00e0 la simplicit\u00e9e de l&#8217;enseignement et assurer la comprehension&#8230; dans ce cas ci: Bowling! On peu aussi comparer \u00e0 une autre manoeuvre commune: Frontside Boardslide, Nollie, speed checks, etc. On se met en partenaire pour l&#8217;\u00e9quivalent du bon vieux Top Gun, on varie en utilisant du terrain vari\u00e9 (les bords de piste, on essaie en switch) et en augmentant la difficult\u00e9 et le d\u00e9fi. Tout \u00e7a soutenue par une analyse individuelle de la performance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5: <strong>Cr\u00e9ation et Suppl\u00e9ment<\/strong> des mouvement: <em><strong>Que puis-je faire comme enseignant pour aider les \u00e9tudiants \u00e0 atteindre leur but(s)?<\/strong> <\/em>Dans ce cas ci on nous emm\u00e8ne dans le parc pour utiliser les modules; des Harry sur les jointures des sauts et g\u00e9rer les pressions associ\u00e9es aux changements de terrain, vraiment le fun et un bon d\u00e9fi pour tous.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donc un mod\u00e8le d&#8217;enseignement simple, individuel et efficace pour une progression plus rapide et une exp\u00e9rience durable avec une progression similaire au mod\u00e8le Canadien du d\u00e9veloppement des habilit\u00e9e motrice (IARCV). Bravo les Suisses; tr\u00e8s bonne pr\u00e9sentation. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luc B\u00e9langer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Journ\u00e9e 3 du congr\u00e8s Interski et aujourd&#8217;hui j&#8217;ai eu le plaisir d&#8217;assister \u00e0 la session sur neige de l&#8217;\u00e9quipe Suisse, un pays qui est toujours tr\u00e8s branch\u00e9 et toujours en recherche d&#8217;innovation pour am\u00e9liorer l&#8217;experience des \u00e9tudiants des \u00e9coles de glisse de la Suisse, c&#8217;est bien aussi de jaser en Fran\u00e7ais avec eux, un de&hellip;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[65,58],"tags":[],"class_list":["post-17565","post","type-post","status-publish","format-standard","hentry","category-casi-interski-fr","category-casi-interski"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/posts\/17565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/comments?post=17565"}],"version-history":[{"count":1,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/posts\/17565\/revisions"}],"predecessor-version":[{"id":17793,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/posts\/17565\/revisions\/17793"}],"wp:attachment":[{"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/media?parent=17565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/categories?post=17565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casi-acms.com\/fr\/wp-json\/wp\/v2\/tags?post=17565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}